{"id":1034,"date":"2020-02-02T16:03:23","date_gmt":"2020-02-02T15:03:23","guid":{"rendered":"http:\/\/wp13489528.server-he.de\/?p=1034"},"modified":"2020-02-02T16:03:23","modified_gmt":"2020-02-02T15:03:23","slug":"auswaertsspieltag-in-boeckingen","status":"publish","type":"post","link":"https:\/\/www.tsv-muenchingen.de\/volleyball\/2020\/02\/02\/auswaertsspieltag-in-boeckingen\/","title":{"rendered":"Ausw\u00e4rtsspieltag in B\u00f6ckingen"},"content":{"rendered":"\n<p>Am 02.02.2020 fuhr die SG M\u00fctzingen 2 zum Ausw\u00e4rtsspieltag beim Tabellenzweiten, der TG B\u00f6ckingen.<br><br>Wie beim Hinspiel im Oktober 2019 entwickelte sich der 1. Satz zu einem  spannenden Kopf-an-Kopf-Rennen, den die SGlerinnen mit 25:22 f\u00fcr sich  entscheiden konnten. Bis zur Mitte des 2. Satzes blieb die Partie eng,  letztendlich aber unterlag die SG mit 17:25. Die Gastgeberinnen aus  B\u00f6ckingen kamen immer besser ins Spiel. Im 3. Satz hatte die SG dem  wenig entgegenzusetzen: Die Fehler h\u00e4uften sich, wichtige Aufschl\u00e4ge  gingen aus oder ins Netz. Das Satzergebnis von 13:25 spricht f\u00fcr sich.  Im 4. Satz erfolgte nochmals ein Aufb\u00e4umen. Doch die TG B\u00f6ckingen war  auch diesmal zu stark und gewann Satz 4 mit 25:22 und damit die Partie  mit 3:1.<br> <br>Das n\u00e4chste Spiel findet am 23.02.2020 um 12 Uhr gegen SpVgg Besigheim in der Neckarhalle in Besigheim statt. <br> <br>Es spielten: Nathalie, Jessi, Angela, Carina, Monja, R\u00f6schi, Luisa, B\u00e4rbel  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am 02.02.2020 fuhr die SG M\u00fctzingen 2 zum Ausw\u00e4rtsspieltag beim Tabellenzweiten, der TG B\u00f6ckingen. Wie beim Hinspiel im Oktober 2019 entwickelte sich der 1. Satz zu einem spannenden Kopf-an-Kopf-Rennen, den die SGlerinnen mit 25:22 f\u00fcr sich entscheiden konnten. Bis zur <a class=\"more-link\" href=\"https:\/\/www.tsv-muenchingen.de\/volleyball\/2020\/02\/02\/auswaertsspieltag-in-boeckingen\/\"><span class=\"screen-reader-text\">  Ausw\u00e4rtsspieltag in B\u00f6ckingen<\/span> weiterlesen<span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[25,26],"tags":[30,32,35],"class_list":["post-1034","post","type-post","status-publish","format-standard","hentry","category-archiv","category-bericht","tag-30","tag-damen","tag-spieltag"],"publishpress_future_action":{"enabled":false,"date":"2026-08-13 19:08:28","action":"category","newStatus":"draft","terms":[108],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.tsv-muenchingen.de\/volleyball\/wp-json\/wp\/v2\/posts\/1034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tsv-muenchingen.de\/volleyball\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tsv-muenchingen.de\/volleyball\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tsv-muenchingen.de\/volleyball\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tsv-muenchingen.de\/volleyball\/wp-json\/wp\/v2\/comments?post=1034"}],"version-history":[{"count":0,"href":"https:\/\/www.tsv-muenchingen.de\/volleyball\/wp-json\/wp\/v2\/posts\/1034\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.tsv-muenchingen.de\/volleyball\/wp-json\/wp\/v2\/media?parent=1034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tsv-muenchingen.de\/volleyball\/wp-json\/wp\/v2\/categories?post=1034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tsv-muenchingen.de\/volleyball\/wp-json\/wp\/v2\/tags?post=1034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}